{"id":7755,"date":"2018-08-08T14:53:23","date_gmt":"2018-08-08T14:53:23","guid":{"rendered":"http:\/\/fmriachuelo.com.ar\/?p=7755"},"modified":"2018-08-08T14:53:23","modified_gmt":"2018-08-08T14:53:23","slug":"tercer-marcha-de-los-movimientos-sociales-por-san-cayetano","status":"publish","type":"post","link":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/2018\/08\/08\/tercer-marcha-de-los-movimientos-sociales-por-san-cayetano\/","title":{"rendered":"TERCER MARCHA DE LOS MOVIMIENTOS SOCIALES POR SAN CAYETANO"},"content":{"rendered":"<p><strong>[FM Riachuelo 08\/08\/2018]<\/strong>\u00a0<strong>Este martes se realiz\u00f3 la marcha de los movimientos sociales a San Cayetano (Patrono del Trabajo), en Liniers. El campo popular, concentr\u00f3 desde muy temprano con las diferentes organizaciones \u00a0de la econom\u00eda popular para culminar con un acto en \u00a0Plaza de Mayo.<\/strong><\/p>\n<p>En Liniers, se pod\u00eda ver llegar a las columnas de las organizaciones que participaron, preparando carteles, banderas para lo que ser\u00eda el desarrollo de la caravana, en una larga caminata de 13 km, donde se pidi\u00f3 por los cinco proyectos de ley presentados sobre la emergencia social, alimentaria, infraestructura, de adicciones, y la \u00a0ley de agricultura familiar.<\/p>\n<p>La marcha se desarroll\u00f3 a partir de las 8 de la ma\u00f1ana con la organizaci\u00f3n a cargo de la Confederaci\u00f3n de Trabajadores de la Econom\u00eda Popular (CTEP), el\u00a0 Movimiento Barrios de Pie y la\u00a0 Corriente Clasista y Combativa (CCC), junto a otras organizaciones como la de los Pescadores de la UPI de Punta Indio y diferentes sindicatos que vienen acompa\u00f1ando, la lucha y la organizaci\u00f3n en las calles.<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7761 size-large aligncenter\" src=\"http:\/\/fmriachuelo.com.ar\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-07-at-18.23.52-1024x682.jpeg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"http:\/\/fmriachuelo.it10.com.ar\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-07-at-18.23.52-1024x682.jpeg 1024w, http:\/\/fmriachuelo.it10.com.ar\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-07-at-18.23.52-300x200.jpeg 300w, http:\/\/fmriachuelo.it10.com.ar\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-07-at-18.23.52-768x512.jpeg 768w, http:\/\/fmriachuelo.it10.com.ar\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-07-at-18.23.52-750x500.jpeg 750w, http:\/\/fmriachuelo.it10.com.ar\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-07-at-18.23.52-1140x760.jpeg 1140w, http:\/\/fmriachuelo.it10.com.ar\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-07-at-18.23.52.jpeg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>Los trabajadores de las distintas unidades productivas de la econom\u00eda popular, se juntaron en un d\u00eda\u00a0 tan representativo, bajo la consigna \u201cEl hambre no se tolera, la dignidad no se negocia\u201d, No al Fondo Monetario\u00a0 y por Paz, Pan, \u00a0Tierra, Techo y Trabajo que destaca la incesante lucha que vienen dando los movimientos populares, \u00a0ante la desigualdad que va creciendo con estas pol\u00edticas de ajuste.<\/p>\n<p>Fm Riachuelo, estuvo participando desde las primeras horas como cada a\u00f1o, all\u00ed hablamos con Rodolfo \u201cNegro\u201d Morales \u00a0de la Unidad Productiva Pipinas, que manifest\u00f3: <strong><em>\u201cNos est\u00e1n matando de a poquito, y por eso venimos acompa\u00f1ar a todos los trabajadores del pa\u00eds\u201d.<\/em><\/strong><\/p>\n<p>Luego entrevistamos a \u00a0Hugo \u201cCachorro\u201d Godoy, Secretario General de Ate Nacional, qui\u00e9n acompa\u00f1o la movilizaci\u00f3n y\u00a0 expres\u00f3: \u201c<strong><em>la importancia de esta marcha junto a la \u00a0unidad de la clase trabajadora\u00a0 en las calles, por una nueva construcci\u00f3n de modelo sindical\u201d. <\/em><\/strong><\/p>\n<p>Por otro lado, Conversamos con Jaqueline Flores, referente del Movimiento de Trabajadores Excluidos (CTEP) que afirmo <strong><em>\u201cNo estamos dispuestos a resignarnos, nos costara lo que nos costara, pero si tenemos algo bien en claro, que el futuro de esta patria esta en nuestros hijos, no estamos dispuesto a entregar la patria\u201d.<\/em><\/strong><\/p>\n<p>La caravana contin\u00fao su recorrido por \u00a0la Av. Rivadavia en donde se pod\u00edan ver marchar a \u00a0las diferentes columnas de organizaciones y sindicatos que acompa\u00f1aron la movilizaci\u00f3n para terminar alrededor del mediod\u00eda, \u00a0en Plaza de Mayo, donde se arm\u00f3 un escenario de cierre de la jornada.<\/p>\n<p>A partir de las 14 hs comenzaron a llegar las columnas, que se sumaron a la numerosa cantidad de organizaciones presentes en la Plaza, y se dio comienzo a los discursos. El acto fue encabezado por tres oradores, Daniel Men\u00e9ndez de Barrios de Pie, Juan Carlos Alderete de la Corriente Clasista y Combativa\u00a0 y por \u00faltimo concluyo la jornada con el discurso de Esteban \u201cGringo\u201d Castro, Secretario general de la Confederaci\u00f3n de los Trabajadores de la Econom\u00eda Popular.<\/p>\n<p><strong><em>Por \u00faltimo, con el grito de todos los presente pidiendo Paz, Pan, Techo, Tierra y Trabajo se entonaron las estrofas del Himno Nacional.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong><a href=\"http:\/\/fmriachuelo.com.ar\/blog\/2018\/08\/07\/marcha-san-cayetano-sin-poder-popular-no-hay-proyecto-nacional\/\">NOTA DEL ACTO CENTRAL<\/a><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[FM Riachuelo 08\/08\/2018]\u00a0Este martes se realiz\u00f3 la marcha de los movimientos sociales a San Cayetano (Patrono del Trabajo), en Liniers. El campo popular, concentr\u00f3 desde muy temprano con las diferentes organizaciones \u00a0de la econom\u00eda popular para culminar con un acto en \u00a0Plaza de Mayo. En Liniers, se pod\u00eda ver llegar a las columnas de las [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"_joinchat":[],"footnotes":""},"categories":[78,76,74,75],"tags":[],"class_list":["post-7755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-popular","category-salud-comunitaria","category-san-cayetano","category-trabajo"],"_links":{"self":[{"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7755"}],"version-history":[{"count":0,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/media\/7757"}],"wp:attachment":[{"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7755"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}