{"id":20016,"date":"2023-03-01T23:02:08","date_gmt":"2023-03-01T23:02:08","guid":{"rendered":"http:\/\/fmriachuelo.com.ar\/?p=20016"},"modified":"2025-02-26T13:17:13","modified_gmt":"2025-02-26T16:17:13","slug":"recordamos-a-quinquela-martin-en-su-cumpleanos","status":"publish","type":"post","link":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/2023\/03\/01\/recordamos-a-quinquela-martin-en-su-cumpleanos\/","title":{"rendered":"RECORDAMOS A QUINQUELA MART\u00cdN EN SU CUMPLEA\u00d1OS"},"content":{"rendered":"<p><strong>[FM Riachuelo, 01\/03\/2023] Un d\u00eda como hoy pero de 1890 nac\u00eda en nuestro barrio de La Boca el querido pintor Benito Quinquela Mart\u00edn. Invitamos al piso de la FM Riachuelo a Miguel Caruso, ex profesor de la Escuela de Fotograf\u00eda Maestro Quinquela Mart\u00edn, quien adem\u00e1s trabaj\u00f3 junto al artista. Intercambiamos sobre la historia de la escuela y lo que signific\u00f3 la figura de Quinquela para el barrio con su solidaridad.<\/strong><\/p>\n<p>Miguel Caruso, fue estudiante y docente del Curso de Fotograf\u00eda, hoy ya est\u00e1 jubilado. Con mucha emoci\u00f3n nos cont\u00f3 un poco de la historia del Maestro Quinquela y se expres\u00f3 en defensa de la escuela p\u00fablica. <em>\u201cQuinquela ha sido para m\u00ed siempre un ejemplo de vida. Yo tuve oportunidad de conocerlo siendo muy joven y tambi\u00e9n tuve la posibilidad, por mi especialidad de fotograf\u00eda, de reproducir muchas de las obras de \u00e9l. La importancia que ten\u00eda Quinquela era mucha. \u00c9l convocaba para hacer alguna obra solidaria, como conseguir un Tom\u00f3grafo para el Hospital Argerich o alg\u00fan equipamiento, y todo el mundo acud\u00eda para hacer una gran campa\u00f1a. Convocaba a colegas, artistas importantes del pa\u00eds, para que donaran sus obras, las vend\u00edan y con lo recaudado se hac\u00eda esta obra de bien.\u201d<\/em><\/p>\n<p>Entre an\u00e9cdotas sobre el maestro Quinquela tambi\u00e9n nos cont\u00f3 un poco de su historia de vida. Fue primero estudiante, luego profesor y hoy sigue colaborando con la escuela que le brind\u00f3 las herramientas para forjar su futuro. <em>\u201cYo soy un agradecido a lo que es la ense\u00f1anza p\u00fablica, porque yo he podido avanzar en mi vida y se lo debo todo a la escuela p\u00fablica. Eso es algo que los argentinos tenemos que valorar, que a veces se nos pasa un poco por alto, pero creo que es una de las virtudes m\u00e1s grandes que tiene este pa\u00eds.\u201d<\/em><br \/>\n<em> Tambi\u00e9n se tom\u00f3 el tiempo para hablar de nuestro barrio. \u201cCuando digo la Boca es la Boca con may\u00fasculas. No por nada se conoce a nivel internacional. Yo digo siempre que una vez vine a la Boca y me qued\u00e9 para siempre, a pesar de que no soy del barrio, no vivo en la Boca, pero es como si fuera mi barrio natal porque he dado muchos a\u00f1os de mi vida en sentirme parte de este barrio. Y valoro mucho la actitud solidaria que he visto en este barrio y no en otros.\u201d<\/em><\/p>\n<p>Para cerrar nos aclara que esta fecha en que se festeja el cumplea\u00f1os de maestro, la cual coincide con su propio natalicio, es la fecha en la que fue anotado al ser adoptado por la familia Quinquela, <em>\u201cDe esa familia que lo adopt\u00f3 se desarroll\u00f3 Quinquela Mart\u00edn y fue lo grande que fue. A trav\u00e9s de la lucha, el sacrificio y la constancia, que si no lo hubiera tenido no hubiera llegado a ser lo que fue\u201d y luego agreg\u00f3 \u201cles agradezco la posibilidad de contar todo esto que han escuchado y que a veces no se sabe, pero es algo muy importante. Ojal\u00e1 que alguno que est\u00e9 medio distra\u00eddo esto le llame la atenci\u00f3n y tambi\u00e9n se ponga a trabajar y a ponerse al servicio de los dem\u00e1s que es la mejor forma de vivir.\u201d<\/em><\/p>\n<p><a href=\"https:\/\/ar.radiocut.fm\/audiocut\/recordamos-a-quinquela-martin-en-su-cumpleanos\/\">Escucha la entrevista completa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[FM Riachuelo, 01\/03\/2023] Un d\u00eda como hoy pero de 1890 nac\u00eda en nuestro barrio de La Boca el querido pintor Benito Quinquela Mart\u00edn. Invitamos al piso de la FM Riachuelo a Miguel Caruso, ex profesor de la Escuela de Fotograf\u00eda Maestro Quinquela Mart\u00edn, quien adem\u00e1s trabaj\u00f3 junto al artista. Intercambiamos sobre la historia de la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":20017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"_joinchat":[],"footnotes":""},"categories":[58],"tags":[152,120],"class_list":["post-20016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticiariachuelo","tag-cultura","tag-la-boca"],"_links":{"self":[{"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/20016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=20016"}],"version-history":[{"count":1,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/20016\/revisions"}],"predecessor-version":[{"id":22117,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/20016\/revisions\/22117"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/media\/20017"}],"wp:attachment":[{"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=20016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=20016"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/fmriachuelo.it10.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=20016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}